{"id":14,"date":"2014-10-02T09:48:54","date_gmt":"2014-10-02T09:48:54","guid":{"rendered":"http:\/\/software.sil.org\/glyssen\/?page_id=14"},"modified":"2016-05-23T14:35:38","modified_gmt":"2016-05-23T18:35:38","slug":"contact","status":"publish","type":"page","link":"https:\/\/software.sil.org\/glyssen\/about\/contact\/","title":{"rendered":"Contact"},"content":{"rendered":"<p>If you have a bug report, feature suggestion, or need help using the software please contact us using the form below.<\/p>\n\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f157-o1\" lang=\"en-US\" dir=\"ltr\" data-wpcf7-id=\"157\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/glyssen\/wp-json\/wp\/v2\/pages\/14#wpcf7-f157-o1\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"Contact form\" novalidate=\"novalidate\" data-status=\"init\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"157\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.6\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"en_US\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f157-o1\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/><input type=\"hidden\" name=\"_wpcf7_recaptcha_response\" value=\"\" \/>\n<\/fieldset>\n<p>Your Name (<i>required<\/i>)\n<\/p>\n<p><span class=\"wpcf7-form-control-wrap\" data-name=\"your-name\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"your-name\" \/><\/span>\n<\/p>\n<p>Your Email (<i>required<\/i>)\n<\/p>\n<p><span class=\"wpcf7-form-control-wrap\" data-name=\"your-email\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"email\" name=\"your-email\" \/><\/span>\n<\/p>\n<p>Type\n<\/p>\n<p><span class=\"wpcf7-form-control-wrap\" data-name=\"type\"><select class=\"wpcf7-form-control wpcf7-select wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" name=\"type\"><option value=\"\">&#8212;Please choose an option&#8212;<\/option><option value=\"Download help\">Download help<\/option><option value=\"Installation help\">Installation help<\/option><option value=\"Bug report\">Bug report<\/option><option value=\"Feature suggestion\">Feature suggestion<\/option><option value=\"I want to help develop the software\">I want to help develop the software<\/option><option value=\"General question\">General question<\/option><\/select><\/span>\n<\/p>\n<p>Subject\n<\/p>\n<p><span class=\"wpcf7-form-control-wrap\" data-name=\"your-subject\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"your-subject\" \/><\/span>\n<\/p>\n<p>Your Message\n<\/p>\n<p><span class=\"wpcf7-form-control-wrap\" data-name=\"your-message\"><textarea cols=\"40\" rows=\"10\" maxlength=\"2000\" class=\"wpcf7-form-control wpcf7-textarea\" aria-invalid=\"false\" name=\"your-message\"><\/textarea><\/span>\n<\/p>\n<p>\n\n<\/p>\n<p><input class=\"wpcf7-form-control wpcf7-submit has-spinner\" type=\"submit\" value=\"Send\" \/><input type=\"reset\" text=\"Reset\" onclick=\"javascript:grecaptcha.reset();\" \/>\n<\/p><p style=\"display: none !important;\" class=\"akismet-fields-container\" data-prefix=\"_wpcf7_ak_\"><label>&#916;<textarea name=\"_wpcf7_ak_hp_textarea\" cols=\"45\" rows=\"8\" maxlength=\"100\"><\/textarea><\/label><input type=\"hidden\" id=\"ak_js_1\" name=\"_wpcf7_ak_js\" value=\"153\"\/><script type=\"text\/javascript\">\n\/* <![CDATA[ *\/\ndocument.getElementById( \"ak_js_1\" ).setAttribute( \"value\", ( new Date() ).getTime() );\n\/* ]]> *\/\n<\/script>\n<\/p><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<\/form>\n<\/div>\n\n","protected":false},"excerpt":{"rendered":"<p>If you have a bug report, feature suggestion, or need help using the software please contact us using the form below.<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":12,"menu_order":0,"comment_status":"closed","ping_status":"open","template":"","meta":{"_acf_changed":false,"hide_sidebar":false,"hide_h1":false,"footnotes":""},"class_list":["post-14","page","type-page","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/software.sil.org\/glyssen\/wp-json\/wp\/v2\/pages\/14","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/software.sil.org\/glyssen\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/software.sil.org\/glyssen\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/software.sil.org\/glyssen\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/software.sil.org\/glyssen\/wp-json\/wp\/v2\/comments?post=14"}],"version-history":[{"count":6,"href":"https:\/\/software.sil.org\/glyssen\/wp-json\/wp\/v2\/pages\/14\/revisions"}],"predecessor-version":[{"id":188,"href":"https:\/\/software.sil.org\/glyssen\/wp-json\/wp\/v2\/pages\/14\/revisions\/188"}],"up":[{"embeddable":true,"href":"https:\/\/software.sil.org\/glyssen\/wp-json\/wp\/v2\/pages\/12"}],"wp:attachment":[{"href":"https:\/\/software.sil.org\/glyssen\/wp-json\/wp\/v2\/media?parent=14"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}